{"id":13806,"date":"2026-02-09T10:42:00","date_gmt":"2026-02-09T09:42:00","guid":{"rendered":"https:\/\/lamarinabj.com\/?p=13806"},"modified":"2026-02-09T08:50:10","modified_gmt":"2026-02-09T07:50:10","slug":"hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207","status":"publish","type":"post","link":"https:\/\/lamarinabj.com\/index.php\/2026\/02\/09\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\/","title":{"rendered":"Hebdo BRVM : La BOA B\u00e9nin et la BIIC portent le pavillon national dans un march\u00e9 \u00e0 +2,07 %"},"content":{"rendered":"\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-red-color\"><strong>Bourse, La Marina BJ<\/strong><\/mark> \u2014 <strong><em>La premi\u00e8re semaine pleine du mois de f\u00e9vrier 2026 (2 au 6 )s&rsquo;ach\u00e8ve sur une note d&rsquo;optimisme g\u00e9n\u00e9ralis\u00e9 pour le march\u00e9 financier r\u00e9gional. Dans le sillage d&rsquo;un indice BRVM Composite qui survole les d\u00e9bats avec une progression hebdomadaire de +2,07 %, le contingent b\u00e9ninois a su tirer son \u00e9pingle du jeu. Port\u00e9 par la vigueur de son p\u00f4le bancaire, le B\u00e9nin confirme sa solidit\u00e9 au sein de l&rsquo;UEMOA, avec en premi\u00e8re ligne la Bank of Africa et la BIIC.<\/em><\/strong><\/p>\n\n\n\n<p>Le march\u00e9 r\u00e9gional a affich\u00e9 une vitalit\u00e9 exceptionnelle au cours de cette p\u00e9riode, port\u00e9e par un courant acheteur puissant qui a propuls\u00e9 34 actions dans le vert. L&rsquo;indice BRVM Composite cl\u00f4ture ainsi \u00e0 372,49 points, soit un gain hebdomadaire significatif, tandis que le BRVM 30 suit la cadence avec une hausse de +1,05 %. Dans ce concert de records, o\u00f9 des titres comme Crown Siem ont affol\u00e9 les compteurs avec un bond de +38,68 %, les actifs b\u00e9ninois ont fait preuve d&rsquo;une r\u00e9silience remarquable, parvenant \u00e0 se hisser dans le peloton de t\u00eate des variations positives.<\/p>\n\n\n\n<h2 id=\"la-boa-benin-locomotive-incontestee-de-la-liquidite\" class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-red-color\">La BOA B\u00e9nin, locomotive incontest\u00e9e de la liquidit\u00e9<\/mark><\/h2>\n\n\n\n<p>La Bank of Africa B\u00e9nin (BOAB) termine cette semaine sur une performance de haute vol\u00e9e, confirmant son statut d&rsquo;actif central pour les gestionnaires de portefeuilles. Avec une progression de +1,02 %, le titre se fixe \u00e0 6 965 FCFA lors de la derni\u00e8re s\u00e9ance du 6 f\u00e9vrier, s&rsquo;octroyant la 27\u00e8me place des plus fortes hausses du march\u00e9 r\u00e9gional.<\/p>\n\n\n\n<p>Au-del\u00e0 de la variation du cours, c&rsquo;est la profondeur de son march\u00e9 qui impressionne : la valeur a drain\u00e9 en cinq s\u00e9ances de cotation 150,22 millions de FCFA de transactions pour un volume de 21 625 titres \u00e9chang\u00e9s. Cette liquidit\u00e9 exceptionnelle permet \u00e0 la capitalisation boursi\u00e8re de la banque de se maintenir solidement au-dessus des 282,5 milliards de FCFA.<\/p>\n\n\n\n<h2 id=\"la-biic-benin-et-la-lnb-entre-croissance-et-stabilite\" class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-red-color\">La BIIC B\u00e9nin et la LNB : Entre croissance et stabilit\u00e9<\/mark><\/h2>\n\n\n\n<p>Le dynamisme b\u00e9ninois a \u00e9galement \u00e9t\u00e9 soutenu par la BIIC B\u00e9nin (BICB), qui s&rsquo;adjuge la 29\u00e8me meilleure performance hebdomadaire de la BRVM. En progressant de +0,82 %, la premi\u00e8re banque b\u00e9ninoise en terme de bilan porte son cours de cl\u00f4ture \u00e0 4 940 FCFA pour une capitalisation boursi\u00e8re imposante de 285,3 milliards de FCFA. Avec un volume d&rsquo;\u00e9changes de 4 063 titres, la BIIC confirme son attractivit\u00e9 retrouv\u00e9e apr\u00e8s un d\u00e9but d&rsquo;ann\u00e9e prudent.<\/p>\n\n\n\n<p>De son c\u00f4t\u00e9, la Loterie Nationale du B\u00e9nin (LNB) a jou\u00e9 la carte de la stabilit\u00e9. En d\u00e9pit des fluctuations de la cote, le titre a termin\u00e9 la semaine sans variation \u00e0 3 940 FCFA, int\u00e9grant ainsi le cercle restreint des trois seules valeurs constantes du march\u00e9. Cette neutralit\u00e9, coupl\u00e9e \u00e0 un volume transactionnel de 3 003 titres, t\u00e9moigne d&rsquo;un \u00e9quilibre parfait entre l&rsquo;offre et la demande pour l&rsquo;actif de services.<\/p>\n\n\n\n<h2 id=\"un-marche-de-contrastes-sectoriels\" class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-red-color\">Un march\u00e9 de contrastes sectoriels<\/mark><\/h2>\n\n\n\n<p>Si le contingent b\u00e9ninois a brill\u00e9 par sa stabilit\u00e9 et sa croissance, la physionomie globale de la BRVM r\u00e9v\u00e8le des trajectoires plus heurt\u00e9es. Le secteur industriel a domin\u00e9 les d\u00e9bats, port\u00e9 par les performances de Sicable (+25,64 %) et Unilever (+25,57 %), tandis que le secteur agro-industriel a subi quelques revers, illustr\u00e9s par la chute de la Sitab (-9,05 %) et de la Sode CI (-4,03 %). Le secteur financier r\u00e9gional, bien que globalement positif, a \u00e9galement vu certains acteurs comme Oragroup (-6,61 %? ou BOA Mali (-3,3 %) basculer dans le rouge. En \u00e9vitant ces zones de turbulences, les valeurs b\u00e9ninoises d\u00e9montrent une ma\u00eetrise technique qui rassure les investisseurs.<\/p>\n\n\n\n<p>\u00c0 l&rsquo;issue de cette semaine marathon, la capitalisation boursi\u00e8re globale de la BRVM se hisse \u00e0 14 361 milliards de FCFA. Ce nouveau sommet historique, coupl\u00e9 \u00e0 la performance robuste des actifs b\u00e9ninois, pr\u00e9pare un terrain fertile pour la suite du mois de f\u00e9vrier. Le p\u00f4le bancaire b\u00e9ninois, plus que jamais au c\u0153ur des strat\u00e9gies de placement, semble pr\u00eat \u00e0 transformer l&rsquo;essai pour franchir de nouveaux paliers d\u00e8s l&rsquo;ouverture de la prochaine s\u00e9ance.<\/p>\n","protected":false},"excerpt":{"rendered":"Bourse, La Marina BJ \u2014 La premi\u00e8re semaine pleine du mois de f\u00e9vrier 2026 (2 au 6 )s&rsquo;ach\u00e8ve&hellip;\n","protected":false},"author":8,"featured_media":13807,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"csco_singular_sidebar":"","csco_page_header_type":"standard","csco_appearance_masonry":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[110],"tags":[41,1613,707,836,953],"class_list":{"0":"post-13806","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-business","8":"tag-benin","9":"tag-biic-benin","10":"tag-boa-benin","11":"tag-brvm","12":"tag-lnb","13":"cs-entry","14":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hebdo BRVM : La BOA B\u00e9nin et la BIIC portent le pavillon national dans un march\u00e9 \u00e0 +2,07 % - LA MARINA BJ<\/title>\n<meta name=\"description\" content=\"Dans le sillage d&#039;un indice BRVM Composite qui survole les d\u00e9bats avec une progression hebdomadaire de +2,07 %, le contingent b\u00e9ninois a su tirer son \u00e9pingle du jeu. Port\u00e9 par la vigueur de son p\u00f4le bancaire, le B\u00e9nin confirme sa solidit\u00e9 au sein de l&#039;UEMOA, avec en premi\u00e8re ligne la Bank of Africa et la BIIC.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lamarinabj.com\/index.php\/2026\/02\/09\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hebdo BRVM : La BOA B\u00e9nin et la BIIC portent le pavillon national dans un march\u00e9 \u00e0 +2,07 % - LA MARINA BJ\" \/>\n<meta property=\"og:description\" content=\"Dans le sillage d&#039;un indice BRVM Composite qui survole les d\u00e9bats avec une progression hebdomadaire de +2,07 %, le contingent b\u00e9ninois a su tirer son \u00e9pingle du jeu. Port\u00e9 par la vigueur de son p\u00f4le bancaire, le B\u00e9nin confirme sa solidit\u00e9 au sein de l&#039;UEMOA, avec en premi\u00e8re ligne la Bank of Africa et la BIIC.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lamarinabj.com\/index.php\/2026\/02\/09\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\/\" \/>\n<meta property=\"og:site_name\" content=\"LA MARINA BJ\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-09T09:42:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lamarinabj.com\/wp-content\/uploads\/2026\/02\/sbee-are_20260209_084733_0000.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Marina BJ - Team Business &amp; \u00c9conomie &amp; Finances\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Marina BJ - Team Business &amp; \u00c9conomie &amp; Finances\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/lamarinabj.com\\\/index.php\\\/2026\\\/02\\\/09\\\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lamarinabj.com\\\/index.php\\\/2026\\\/02\\\/09\\\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\\\/\"},\"author\":{\"name\":\"La Marina BJ - Team Business &amp; \u00c9conomie &amp; Finances\",\"@id\":\"https:\\\/\\\/lamarinabj.com\\\/#\\\/schema\\\/person\\\/daecc7fb1eea21418f92763d06a3f4b4\"},\"headline\":\"Hebdo BRVM : La BOA B\u00e9nin et la BIIC portent le pavillon national dans un march\u00e9 \u00e0 +2,07 %\",\"datePublished\":\"2026-02-09T09:42:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lamarinabj.com\\\/index.php\\\/2026\\\/02\\\/09\\\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\\\/\"},\"wordCount\":693,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/lamarinabj.com\\\/index.php\\\/2026\\\/02\\\/09\\\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lamarinabj.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sbee-are_20260209_084733_0000.jpg\",\"keywords\":[\"B\u00e9nin\",\"BIIC B\u00e9nin\",\"Boa B\u00e9nin\",\"BRVM\",\"LNB\"],\"articleSection\":[\"BUSINESS\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lamarinabj.com\\\/index.php\\\/2026\\\/02\\\/09\\\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"SearchResultsPage\"],\"@id\":\"https:\\\/\\\/lamarinabj.com\\\/index.php\\\/2026\\\/02\\\/09\\\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\\\/\",\"url\":\"https:\\\/\\\/lamarinabj.com\\\/index.php\\\/2026\\\/02\\\/09\\\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\\\/\",\"name\":\"Hebdo BRVM : La BOA B\u00e9nin et la BIIC portent le pavillon national dans un march\u00e9 \u00e0 +2,07 % - LA MARINA BJ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lamarinabj.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lamarinabj.com\\\/index.php\\\/2026\\\/02\\\/09\\\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lamarinabj.com\\\/index.php\\\/2026\\\/02\\\/09\\\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lamarinabj.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sbee-are_20260209_084733_0000.jpg\",\"datePublished\":\"2026-02-09T09:42:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lamarinabj.com\\\/#\\\/schema\\\/person\\\/daecc7fb1eea21418f92763d06a3f4b4\"},\"description\":\"Dans le sillage d'un indice BRVM Composite qui survole les d\u00e9bats avec une progression hebdomadaire de +2,07 %, le contingent b\u00e9ninois a su tirer son \u00e9pingle du jeu. Port\u00e9 par la vigueur de son p\u00f4le bancaire, le B\u00e9nin confirme sa solidit\u00e9 au sein de l'UEMOA, avec en premi\u00e8re ligne la Bank of Africa et la BIIC.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lamarinabj.com\\\/index.php\\\/2026\\\/02\\\/09\\\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lamarinabj.com\\\/index.php\\\/2026\\\/02\\\/09\\\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lamarinabj.com\\\/index.php\\\/2026\\\/02\\\/09\\\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lamarinabj.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sbee-are_20260209_084733_0000.jpg\",\"contentUrl\":\"https:\\\/\\\/lamarinabj.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sbee-are_20260209_084733_0000.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lamarinabj.com\\\/index.php\\\/2026\\\/02\\\/09\\\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lamarinabj.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hebdo BRVM : La BOA B\u00e9nin et la BIIC portent le pavillon national dans un march\u00e9 \u00e0 +2,07 %\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lamarinabj.com\\\/#website\",\"url\":\"https:\\\/\\\/lamarinabj.com\\\/\",\"name\":\"LA MARINA BJ\",\"description\":\"Votre portail vers l&#039;information strat\u00e9gique au B\u00e9nin, en Afrique et au-del\u00e0\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lamarinabj.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lamarinabj.com\\\/#\\\/schema\\\/person\\\/daecc7fb1eea21418f92763d06a3f4b4\",\"name\":\"La Marina BJ - Team Business &amp; \u00c9conomie &amp; Finances\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/007be62133093bb48d247a392503beff272bc6a9503872d32895035e0e72b4f7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/007be62133093bb48d247a392503beff272bc6a9503872d32895035e0e72b4f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/007be62133093bb48d247a392503beff272bc6a9503872d32895035e0e72b4f7?s=96&d=mm&r=g\",\"caption\":\"La Marina BJ - Team Business &amp; \u00c9conomie &amp; Finances\"},\"description\":\"La Team \u00c9conomie &amp; Finances de La Marina BJ d\u00e9crypte les dynamiques \u00e9conomiques qui fa\u00e7onnent le B\u00e9nin, l\u2019Afrique et le monde. Compos\u00e9e de journalistes \u00e9conomiques, d\u2019analystes sectoriels et de veilleurs sp\u00e9cialis\u00e9s, elle s\u2019attache \u00e0 rendre lisibles les m\u00e9canismes financiers, les politiques budg\u00e9taires, les r\u00e9formes fiscales et les grandes orientations macro\u00e9conomiques. Son ambition : \u00e9clairer les choix, anticiper les tendances et outiller les d\u00e9cideurs \u2014 publics comme priv\u00e9s \u2014 dans un environnement \u00e9conomique en constante mutation.\",\"url\":\"https:\\\/\\\/lamarinabj.com\\\/index.php\\\/author\\\/ernestine\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hebdo BRVM : La BOA B\u00e9nin et la BIIC portent le pavillon national dans un march\u00e9 \u00e0 +2,07 % - LA MARINA BJ","description":"Dans le sillage d'un indice BRVM Composite qui survole les d\u00e9bats avec une progression hebdomadaire de +2,07 %, le contingent b\u00e9ninois a su tirer son \u00e9pingle du jeu. Port\u00e9 par la vigueur de son p\u00f4le bancaire, le B\u00e9nin confirme sa solidit\u00e9 au sein de l'UEMOA, avec en premi\u00e8re ligne la Bank of Africa et la BIIC.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lamarinabj.com\/index.php\/2026\/02\/09\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\/","og_locale":"fr_FR","og_type":"article","og_title":"Hebdo BRVM : La BOA B\u00e9nin et la BIIC portent le pavillon national dans un march\u00e9 \u00e0 +2,07 % - LA MARINA BJ","og_description":"Dans le sillage d'un indice BRVM Composite qui survole les d\u00e9bats avec une progression hebdomadaire de +2,07 %, le contingent b\u00e9ninois a su tirer son \u00e9pingle du jeu. Port\u00e9 par la vigueur de son p\u00f4le bancaire, le B\u00e9nin confirme sa solidit\u00e9 au sein de l'UEMOA, avec en premi\u00e8re ligne la Bank of Africa et la BIIC.","og_url":"https:\/\/lamarinabj.com\/index.php\/2026\/02\/09\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\/","og_site_name":"LA MARINA BJ","article_published_time":"2026-02-09T09:42:00+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/lamarinabj.com\/wp-content\/uploads\/2026\/02\/sbee-are_20260209_084733_0000.jpg","type":"image\/jpeg"}],"author":"La Marina BJ - Team Business &amp; \u00c9conomie &amp; Finances","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Marina BJ - Team Business &amp; \u00c9conomie &amp; Finances"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/lamarinabj.com\/index.php\/2026\/02\/09\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\/#article","isPartOf":{"@id":"https:\/\/lamarinabj.com\/index.php\/2026\/02\/09\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\/"},"author":{"name":"La Marina BJ - Team Business &amp; \u00c9conomie &amp; Finances","@id":"https:\/\/lamarinabj.com\/#\/schema\/person\/daecc7fb1eea21418f92763d06a3f4b4"},"headline":"Hebdo BRVM : La BOA B\u00e9nin et la BIIC portent le pavillon national dans un march\u00e9 \u00e0 +2,07 %","datePublished":"2026-02-09T09:42:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lamarinabj.com\/index.php\/2026\/02\/09\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\/"},"wordCount":693,"commentCount":0,"image":{"@id":"https:\/\/lamarinabj.com\/index.php\/2026\/02\/09\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\/#primaryimage"},"thumbnailUrl":"https:\/\/lamarinabj.com\/wp-content\/uploads\/2026\/02\/sbee-are_20260209_084733_0000.jpg","keywords":["B\u00e9nin","BIIC B\u00e9nin","Boa B\u00e9nin","BRVM","LNB"],"articleSection":["BUSINESS"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lamarinabj.com\/index.php\/2026\/02\/09\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\/#respond"]}]},{"@type":["WebPage","SearchResultsPage"],"@id":"https:\/\/lamarinabj.com\/index.php\/2026\/02\/09\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\/","url":"https:\/\/lamarinabj.com\/index.php\/2026\/02\/09\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\/","name":"Hebdo BRVM : La BOA B\u00e9nin et la BIIC portent le pavillon national dans un march\u00e9 \u00e0 +2,07 % - LA MARINA BJ","isPartOf":{"@id":"https:\/\/lamarinabj.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lamarinabj.com\/index.php\/2026\/02\/09\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\/#primaryimage"},"image":{"@id":"https:\/\/lamarinabj.com\/index.php\/2026\/02\/09\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\/#primaryimage"},"thumbnailUrl":"https:\/\/lamarinabj.com\/wp-content\/uploads\/2026\/02\/sbee-are_20260209_084733_0000.jpg","datePublished":"2026-02-09T09:42:00+00:00","author":{"@id":"https:\/\/lamarinabj.com\/#\/schema\/person\/daecc7fb1eea21418f92763d06a3f4b4"},"description":"Dans le sillage d'un indice BRVM Composite qui survole les d\u00e9bats avec une progression hebdomadaire de +2,07 %, le contingent b\u00e9ninois a su tirer son \u00e9pingle du jeu. Port\u00e9 par la vigueur de son p\u00f4le bancaire, le B\u00e9nin confirme sa solidit\u00e9 au sein de l'UEMOA, avec en premi\u00e8re ligne la Bank of Africa et la BIIC.","breadcrumb":{"@id":"https:\/\/lamarinabj.com\/index.php\/2026\/02\/09\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lamarinabj.com\/index.php\/2026\/02\/09\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lamarinabj.com\/index.php\/2026\/02\/09\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\/#primaryimage","url":"https:\/\/lamarinabj.com\/wp-content\/uploads\/2026\/02\/sbee-are_20260209_084733_0000.jpg","contentUrl":"https:\/\/lamarinabj.com\/wp-content\/uploads\/2026\/02\/sbee-are_20260209_084733_0000.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/lamarinabj.com\/index.php\/2026\/02\/09\/hebdo-brvm-la-boa-benin-et-la-biic-portent-le-pavillon-national-dans-un-marche-a-207\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lamarinabj.com\/"},{"@type":"ListItem","position":2,"name":"Hebdo BRVM : La BOA B\u00e9nin et la BIIC portent le pavillon national dans un march\u00e9 \u00e0 +2,07 %"}]},{"@type":"WebSite","@id":"https:\/\/lamarinabj.com\/#website","url":"https:\/\/lamarinabj.com\/","name":"LA MARINA BJ","description":"Votre portail vers l&#039;information strat\u00e9gique au B\u00e9nin, en Afrique et au-del\u00e0","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lamarinabj.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/lamarinabj.com\/#\/schema\/person\/daecc7fb1eea21418f92763d06a3f4b4","name":"La Marina BJ - Team Business &amp; \u00c9conomie &amp; Finances","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/007be62133093bb48d247a392503beff272bc6a9503872d32895035e0e72b4f7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/007be62133093bb48d247a392503beff272bc6a9503872d32895035e0e72b4f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/007be62133093bb48d247a392503beff272bc6a9503872d32895035e0e72b4f7?s=96&d=mm&r=g","caption":"La Marina BJ - Team Business &amp; \u00c9conomie &amp; Finances"},"description":"La Team \u00c9conomie &amp; Finances de La Marina BJ d\u00e9crypte les dynamiques \u00e9conomiques qui fa\u00e7onnent le B\u00e9nin, l\u2019Afrique et le monde. Compos\u00e9e de journalistes \u00e9conomiques, d\u2019analystes sectoriels et de veilleurs sp\u00e9cialis\u00e9s, elle s\u2019attache \u00e0 rendre lisibles les m\u00e9canismes financiers, les politiques budg\u00e9taires, les r\u00e9formes fiscales et les grandes orientations macro\u00e9conomiques. Son ambition : \u00e9clairer les choix, anticiper les tendances et outiller les d\u00e9cideurs \u2014 publics comme priv\u00e9s \u2014 dans un environnement \u00e9conomique en constante mutation.","url":"https:\/\/lamarinabj.com\/index.php\/author\/ernestine\/"}]}},"_links":{"self":[{"href":"https:\/\/lamarinabj.com\/index.php\/wp-json\/wp\/v2\/posts\/13806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lamarinabj.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lamarinabj.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lamarinabj.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/lamarinabj.com\/index.php\/wp-json\/wp\/v2\/comments?post=13806"}],"version-history":[{"count":2,"href":"https:\/\/lamarinabj.com\/index.php\/wp-json\/wp\/v2\/posts\/13806\/revisions"}],"predecessor-version":[{"id":13809,"href":"https:\/\/lamarinabj.com\/index.php\/wp-json\/wp\/v2\/posts\/13806\/revisions\/13809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lamarinabj.com\/index.php\/wp-json\/wp\/v2\/media\/13807"}],"wp:attachment":[{"href":"https:\/\/lamarinabj.com\/index.php\/wp-json\/wp\/v2\/media?parent=13806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lamarinabj.com\/index.php\/wp-json\/wp\/v2\/categories?post=13806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lamarinabj.com\/index.php\/wp-json\/wp\/v2\/tags?post=13806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}